{"id":370065,"date":"2021-12-21T17:00:00","date_gmt":"2021-12-21T16:00:00","guid":{"rendered":"https:\/\/www.bwin.it\/it\/news\/?p=370065"},"modified":"2021-12-21T16:12:34","modified_gmt":"2021-12-21T15:12:34","slug":"liverpool-leicester-quote-scommesse-pronostico-22-12-21","status":"publish","type":"post","link":"https:\/\/www.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21","title":{"rendered":"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti"},"content":{"rendered":"\n<p><strong>Liverpool-Leicester \u00e8 un match valevole per i quarti di finale di EFL Cup, la coppa di lega inglese. Ma si dovr\u00e0 fare in primis i conti con giocatori positivi al Covid-19. E da entrambe le parti sono numerosi. Pi\u00f9 per i Foxes fermi ai box dal 12 dicembre, giorno in cui hanno disputato il loro ultimo incontro vinto per 4-0 sul Newcastle. Poi rinviate per focolaio sia Leicester-Tottenham che Everton-Leicester. Si riuscir\u00e0 a giocare ad Anfield. Molto probabilmente s\u00ec. Il pronostico. di Liverpool-Leicester<\/strong>.<\/p>\n\n\n\n<p><strong>Quote del:<\/strong> 21\/12\/21<\/p>\n\n\n\n<p><strong>Fischio d\u2019inizio:<\/strong> mercoled\u00ec 22 dicembre, ore 20.45<\/p>\n\n\n\n<p><strong>Sede:<\/strong> Anfield, Liverpool<\/p>\n\n\n\n<p>Liverpool e Leicester City si contendono un posto nelle semifinali della EFL Cup. I Reds sono in ottima forma al momento e vorranno mostrare di essere sul pezzo in tutte le competizioni a cominciare proprio dalla coppa di Lega. La squadra di Klopp ha di fatto visto terminare un filotto di otto vittorie consecutive, tra tutte le competizioni giocate, in seguito al pareggio per 2-2 contro il Tottenham Hotspur della scorsa domenica in Premier League. Tuttavia, la squadra di Jurgen Klopp \u00e8 imbattuta negli ultimi 18 anni in casa&nbsp;in questo torneo. E il Liverpool ha vinto sei degli ultimi otto incontri con il Leicester. Bisogna tornare al maggio 2000 per registrare l&#8217;ultima vittoria dei Foxes ad Anfield.<\/p>\n\n\n\n<p>Ed \u00e8 un Leicester che peraltro sta lottando con il Covid, reo di aver messo fuori gioco numerosi titolari della squadra. Gli uomini di Brendan Rodgers occupano un modesto nono posto in campionato e non sono riusciti a replicare le scintillanti partenze delle stagioni passate.&nbsp;Sebbene, nell&#8217;ultima gara contro il Newcastle il 4-0 infilato deve sicuramente imposto fiducia.<\/p>\n\n\n\n\n\n\n\n<h2 class=\"gb-headline gb-headline-72cbe92b gb-headline-text\">Le probabili formazioni<\/h2>\n\n\n\n<p>Lato Liverpool Thiago Alcantara, Virgil Van Dijk, Fabinho e Curtis Jones sono tutti risultati positivi al test per il virus ed \u00e8 improbabile che prendano parte alla sfida contro i Foxes. Il Liverpool ha sicuramente avuto pi\u00f9 fortuna con gli infortuni in questa stagione rispetto alla scorsa.\u00a0Harvey Elliott rimane l&#8217;unico assente a lungo termine. Al quale si aggiunge temporaneamente Jordan Henderson, out.<\/p>\n\n\n\n<p>Le truppa di Brendan Rodgers \u00e8 arrivata a questo match di EFL Cup battendo il Brighton ai rigori, ma ora ci sar\u00e0 un pesce molto pi\u00f9 grande da friggere. E per quanto riguarda gli assenti, Benkovic, Choudhury, Iheanacho, Lookman, Parez e Vestergaard sono risultati positivi al COVID-19, mentre Justin e Fofana sono fuori per infortuni. <\/p>\n\n\n\n<p><strong>Liverpool (4-3-3)<\/strong>: Kelleher;\u00a0Tsimikas, Joe Gomez, Matip, Williams;\u00a0Alex-Oxlade Chamberlain, Morton, Naby Keita;\u00a0Firmino, Gordon, Minamino. All. Klopp.<\/p>\n\n\n\n<p><strong>Leicester (4-2-3-1)<\/strong>: Kasper Schmeichel, Albrighton, Amartey, Bertrand, Thomas, Tielemans, Ndidi, Barnes, Maddison, Dewsbury-Hall, Daka. All. Rodgers.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-f03a7c06 gb-headline-text\">Liverpool-Leicester, quote e pronostico<\/h2>\n\n\n\n<p>Il Liverpool \u00e8 in uno stato di forma eccezionale e difficilmente sbaglier\u00e0 questa partita. Davvero ancora troppe le defezioni per la squadra di Rodgers. I Reds hanno un piede nelle semifinali secondo il nostro modesto parere e <a href=\"https:\/\/www.bwin.it\/it\/sports\/calcio-4\/scommesse\/inghilterra-14\/efl-cup-102782\">le quote sull&#8217;EFL Cup<\/a> danno chiaramente favoriti i ragazzi di Klopp. Il livello di prestazioni nonostante alcune modifiche alla squadra insieme ad un Leicester gravemente colpito dal Covid-19 e dagli infortuni sono due fattori sufficienti per farci credere ad una comoda vittoria dei Reds per 2-0, uguale conquista delle semifinali della competizione. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liverpool-Leicester \u00e8 un match valevole per i quarti di finale di EFL Cup, la coppa di lega inglese. Ma si dovr\u00e0 fare in primis i conti con giocatori positivi al Covid-19. E da entrambe le parti sono numerosi. Pi\u00f9 per i Foxes fermi ai box dal 12 dicembre, giorno in &#8230; <a title=\"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti\" class=\"read-more\" href=\"https:\/\/www.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\" aria-label=\"Per saperne di pi\u00f9 su Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti\">Leggi tutto<\/a><\/p>\n","protected":false},"author":216,"featured_media":370101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,3771],"tags":[],"class_list":["post-370065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coppe","category-calcio","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21<\/title>\n<meta name=\"description\" content=\"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21\" \/>\n<meta property=\"og:description\" content=\"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\" \/>\n<meta property=\"og:site_name\" content=\"bwin news\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-21T15:12:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newscdn.fitting-solutions.at\/it\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg?strip=all&lossy=1&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Donato De Sena\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Donato De Sena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#article\",\"isPartOf\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\"},\"author\":{\"name\":\"Donato De Sena\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/472b3a6591bca5a388113b34f09daf4f\"},\"headline\":\"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti\",\"datePublished\":\"2021-12-21T16:00:00+00:00\",\"dateModified\":\"2021-12-21T15:12:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg\",\"articleSection\":[\"Coppe\",\"Calcio\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.bwin.it\/it\/news\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\",\"url\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\",\"name\":\"Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21\",\"isPartOf\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg\",\"datePublished\":\"2021-12-21T16:00:00+00:00\",\"dateModified\":\"2021-12-21T15:12:34+00:00\",\"description\":\"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.\",\"breadcrumb\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage\",\"url\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg\",\"contentUrl\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Liverpool-Leicester EFL Cup quarti di finale 2021-2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sports.bwin.it\/it\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calcio\",\"item\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coppe\",\"item\":\"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#website\",\"url\":\"https:\/\/sports.bwin.it\/it\/news\/\",\"name\":\"bwin news\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sports.bwin.it\/it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\",\"name\":\"bwin news\",\"url\":\"https:\/\/sports.bwin.it\/it\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png\",\"contentUrl\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png\",\"width\":1060,\"height\":400,\"caption\":\"bwin news\"},\"image\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/472b3a6591bca5a388113b34f09daf4f\",\"name\":\"Donato De Sena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8f01ac2564dc0b8b5fded60431f35bcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8f01ac2564dc0b8b5fded60431f35bcb?s=96&d=mm&r=g\",\"caption\":\"Donato De Sena\"},\"url\":\"https:\/\/www.bwin.it\/it\/news\/author\/d-desena\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21","description":"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21","og_locale":"it_IT","og_type":"article","og_title":"Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21","og_description":"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.","og_url":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21","og_site_name":"bwin news","article_published_time":"2021-12-21T16:00:00+00:00","article_modified_time":"2021-12-21T15:12:34+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/newscdn.fitting-solutions.at\/it\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg?strip=all&lossy=1&ssl=1","type":"image\/jpeg"}],"author":"Donato De Sena","twitter_misc":{"Scritto da":"Donato De Sena","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#article","isPartOf":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21"},"author":{"name":"Donato De Sena","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/472b3a6591bca5a388113b34f09daf4f"},"headline":"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti","datePublished":"2021-12-21T16:00:00+00:00","dateModified":"2021-12-21T15:12:34+00:00","mainEntityOfPage":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21"},"wordCount":527,"publisher":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#organization"},"image":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage"},"thumbnailUrl":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg","articleSection":["Coppe","Calcio"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.bwin.it\/it\/news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21","url":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21","name":"Liverpool-Leicester: quote scommesse e pronostico EFL Cup 22\/12\/21","isPartOf":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage"},"image":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage"},"thumbnailUrl":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg","datePublished":"2021-12-21T16:00:00+00:00","dateModified":"2021-12-21T15:12:34+00:00","description":"Le probabili formazioni, le quote scommesse e il pronostico di Liverpool-Leicester match valido per i quarti di finale di EFL Cup 2021-2022.","breadcrumb":{"@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#primaryimage","url":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg","contentUrl":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2021\/12\/Liverpool-Leicester-EFL-Cup-quarti-di-finale-2021-2022.jpg","width":1200,"height":800,"caption":"Liverpool-Leicester EFL Cup quarti di finale 2021-2022"},{"@type":"BreadcrumbList","@id":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe\/liverpool-leicester-quote-scommesse-pronostico-22-12-21#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sports.bwin.it\/it\/news\/"},{"@type":"ListItem","position":2,"name":"Calcio","item":"https:\/\/sports.bwin.it\/it\/news\/calcio"},{"@type":"ListItem","position":3,"name":"Coppe","item":"https:\/\/sports.bwin.it\/it\/news\/calcio\/coppe"},{"@type":"ListItem","position":4,"name":"Liverpool-Leicester: il Covid la fa da padrone e i Reds sono favoriti"}]},{"@type":"WebSite","@id":"https:\/\/sports.bwin.it\/it\/news\/#website","url":"https:\/\/sports.bwin.it\/it\/news\/","name":"bwin news","description":"","publisher":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sports.bwin.it\/it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sports.bwin.it\/it\/news\/#organization","name":"bwin news","url":"https:\/\/sports.bwin.it\/it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png","contentUrl":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png","width":1060,"height":400,"caption":"bwin news"},"image":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/472b3a6591bca5a388113b34f09daf4f","name":"Donato De Sena","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8f01ac2564dc0b8b5fded60431f35bcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f01ac2564dc0b8b5fded60431f35bcb?s=96&d=mm&r=g","caption":"Donato De Sena"},"url":"https:\/\/www.bwin.it\/it\/news\/author\/d-desena"}]}},"_links":{"self":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/370065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/comments?post=370065"}],"version-history":[{"count":16,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/370065\/revisions"}],"predecessor-version":[{"id":370539,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/370065\/revisions\/370539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/media\/370101"}],"wp:attachment":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/media?parent=370065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/categories?post=370065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/tags?post=370065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}