{"id":585761,"date":"2026-07-13T20:57:52","date_gmt":"2026-07-13T18:57:52","guid":{"rendered":"https:\/\/www.bwin.it\/it\/news\/?p=585761"},"modified":"2026-07-13T20:57:53","modified_gmt":"2026-07-13T18:57:53","slug":"quote-francia-spagna-scommesse-pronostico-14-7-2026","status":"publish","type":"post","link":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026","title":{"rendered":"Francia-Spagna: semifinale tra le grandi favorite del Mondiale"},"content":{"rendered":"<p><strong>Transalpini e iberici si contenderanno un posto per la finalissima della massima rassegna iridata. Mbapp\u00e9 continua a segnare senza sosta, ma la Roja ha subito un solo gol finora. Le quote Francia-Spagna vedono favoriti di poco i Bleus.<\/strong><\/p>\n<p><strong>Quote Francia-Spagna del:<\/strong> 13\/7\/2026<\/p>\n<p><strong>Fischio d\u2019inizio:<\/strong> marted\u00ec 14 luglio, ore 21.00<\/p>\n<p><strong>Sede:<\/strong> AT&amp;T Stadium, Arlington<\/p>\n<h2>La presentazione<\/h2>\n<p>La prima semifinale del Mondiale sar\u00e0 Francia-Spagna, in programma marted\u00ec 14 luglio alle ore 21.00 presso l\u2019AT&amp;T Stadium. Gi\u00e0 dalla vigilia del torneo sia i Bleus sia le Furie Rosse erano tra i primi indiziati per la vittoria del titolo, ma solo una delle due formazioni potr\u00e0 effettivamente giocarsi la finalissima. I transalpini non hanno avuto grandi patemi nel gruppo I, dove hanno battuto il Senegal per 3-1, l\u2019Iraq per 3-0 e la Norvegia per 1-4. Ai sedicesimi di finale \u00e8 stata la Svezia a cadere, con il punteggio di 3-0, poi agli ottavi i ragazzi di Didier Deschamps si sono imposti sul Paraguay per 0-1. In occasione dei quarti, invece, la Francia ha battuto un pregevole Marocco per 2-0. Nel complesso i vice-campioni del mondo in carica hanno messo dunque a segno 16 gol, subendone 2. Met\u00e0 delle reti \u00e8 stata realizzata dal solo Kylian Mbapp\u00e9.<\/p>\n<p>La Spagna aveva iniziato male l\u2019avventura iridata pareggiando per 0-0 con il sorprendente Capo Verde. In seguito la Roja ha raddrizzato la situazione nel girone H superando l\u2019Arabia Saudita per 4-0 e l\u2019Uruguay per 0-1. All\u2019inizio della fase ad eliminazione diretta la formazione guidata da Luis de la Fuente ha avuto ragione dell\u2019Austria, sconfitta per 3-0. Agli ottavi le Furie Rosse hanno eliminato invece il Portogallo con un secco 0-1, mentre pi\u00f9 combattuta \u00e8 stata la gara dei quarti con il Belgio, battuto con il risultato di 2-1. I gol all\u2019attivo sono in totale 11, ma a incuriosire \u00e8 soprattutto il dato sulla difesa, che ha incassato un\u2019unica rete finora, concedendo peraltro a Unai Simon un\u2019imbattibilit\u00e0 durata ben 649 minuti.<\/p>\n<p>L\u2019ultimo precedente tra Francia e Spagna risale al 5 giugno 2025. Nella semifinale della scorsa edizione della Nations League gli iberici vinsero per 5-4. Nel tabellino dei marcatori finirono Nico Williams, Mikel Merino, Lamine Yamal (doppietta), Pedri, Kylian Mbapp\u00e9, Rayan Cherki, un\u2019autorete di Dani Vivian e infine Randal Kolo Muani.<br \/>\n<script src=\"\/\/my.visme.co\/visme-embed.js\"><\/script><\/p>\n<div style=\"width: 100%;\">\n<div class=\"visme_d\" data-url=\"x9mx6rqn-francia-vs-spagna\" data-w=\"1080\" data-h=\"1720\" data-domain=\"my\"><\/div>\n<\/div>\n<h2>Francia-Spagna, quote scommesse e pronostico<\/h2>\n<p>Francia-Spagna pu\u00f2 considerarsi una finale anticipata. Secondo le <a href=\"https:\/\/www.bwin.it\/it\/sports\/calcio-4\/scommesse\/mondo-6\/mondiali-2026-0:14\">quote sui Mondiali<\/a> i transalpini sono leggermente favoriti. Il segno 1 \u00e8 indicato a 2.30, il segno 2 a 3.25 e il segno X a 3.10. Stando alle statistiche sia l\u2019Under 2.5 sia l\u2019Over 2.5 sono dati a 1.85. Lo scenario del Gol Gol viene proposto a 1.65. Il risultato esatto considerato meno improbabile coincide con l\u20191-1, offerto a 5.75, mentre lo 0-0 \u00e8 bancato a 10.00 e il 2-2 a 12.00. L\u20191-0 e il 2-1 per la Francia sono quotati a 8.75 e il 2-0 \u00e8 offerto a 11.50. Lo 0-1 per la Spagna, invece, \u00e8 segnato in lavagna a 10.50.<\/p>\n<p><em>Crediti immagine: IMAGO<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transalpini e iberici si contenderanno un posto per la finalissima della massima rassegna iridata. Mbapp\u00e9 continua a segnare senza sosta, ma la Roja ha subito un solo gol finora. Le quote Francia-Spagna vedono favoriti di poco i Bleus. Quote Francia-Spagna del: 13\/7\/2026 Fischio d\u2019inizio: marted\u00ec 14 luglio, ore 21.00 Sede: &#8230; <a title=\"Francia-Spagna: semifinale tra le grandi favorite del Mondiale\" class=\"read-more\" href=\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\" aria-label=\"Per saperne di pi\u00f9 su Francia-Spagna: semifinale tra le grandi favorite del Mondiale\">Leggi tutto<\/a><\/p>\n","protected":false},"author":225,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4182,7169],"tags":[],"class_list":["post-585761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infografiche","category-mondiali-2026","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>quote Francia Spagna: il pronostico sui Bleus<\/title>\n<meta name=\"description\" content=\"Le quote Francia Spagna: il pronostico sull&#039;atteso incontro valido per la prima semifinale dei Mondiali 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"quote Francia Spagna: il pronostico sui Bleus\" \/>\n<meta property=\"og:description\" content=\"Le quote Francia Spagna: il pronostico sull&#039;atteso incontro valido per la prima semifinale dei Mondiali 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\" \/>\n<meta property=\"og:site_name\" content=\"bwin news\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T18:57:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T18:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/og-image\/immagine-scommesse-francia-spagna-bwin-news-watermarked-b22c3735f1ea642385f343e5cf117991.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1874\" \/>\n\t<meta property=\"og:image:height\" content=\"1249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emanuele Celeste\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emanuele Celeste\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\"},\"author\":{\"name\":\"Emanuele Celeste\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/fe0357b991a70902eeb82d9f3973e452\"},\"headline\":\"Francia-Spagna: semifinale tra le grandi favorite del Mondiale\",\"datePublished\":\"2026-07-13T18:57:52+00:00\",\"dateModified\":\"2026-07-13T18:57:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\"},\"wordCount\":485,\"publisher\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\"},\"articleSection\":[\"Infografiche sullo Sport e Approfondimenti\",\"Mondiali 2026\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.bwin.it\/it\/news\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\",\"url\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\",\"name\":\"quote Francia Spagna: il pronostico sui Bleus\",\"isPartOf\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#website\"},\"datePublished\":\"2026-07-13T18:57:52+00:00\",\"dateModified\":\"2026-07-13T18:57:53+00:00\",\"description\":\"Le quote Francia Spagna: il pronostico sull'atteso incontro valido per la prima semifinale dei Mondiali 2026.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sports.bwin.it\/it\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiali 2026\",\"item\":\"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Francia-Spagna: semifinale tra le grandi favorite del Mondiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#website\",\"url\":\"https:\/\/sports.bwin.it\/it\/news\/\",\"name\":\"bwin news\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sports.bwin.it\/it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#organization\",\"name\":\"bwin news\",\"url\":\"https:\/\/sports.bwin.it\/it\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png\",\"contentUrl\":\"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png\",\"width\":1060,\"height\":400,\"caption\":\"bwin news\"},\"image\":{\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/fe0357b991a70902eeb82d9f3973e452\",\"name\":\"Emanuele Celeste\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f38a8b15ffff50d003d266ca22a08912?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f38a8b15ffff50d003d266ca22a08912?s=96&d=mm&r=g\",\"caption\":\"Emanuele Celeste\"},\"description\":\"Attivo nel campo della comunicazione e dell'informazione dal 2007. Grazie alla lunga esperienza presso eventi e conferenze pu\u00f2 vantare in bacheca centinaia di interventi radiotelevisivi anche con personaggi del mondo dello spettacolo e dello sport, mentre gli incarichi da social media manager lo hanno portato a scoprire anche gli angoli pi\u00f9 remoti della rete. Non perde mai di vista tutto ci\u00f2 che \u00e8 di attualit\u00e0.\",\"url\":\"https:\/\/www.bwin.it\/it\/news\/author\/e-celeste\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"quote Francia Spagna: il pronostico sui Bleus","description":"Le quote Francia Spagna: il pronostico sull'atteso incontro valido per la prima semifinale dei Mondiali 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026","og_locale":"it_IT","og_type":"article","og_title":"quote Francia Spagna: il pronostico sui Bleus","og_description":"Le quote Francia Spagna: il pronostico sull'atteso incontro valido per la prima semifinale dei Mondiali 2026.","og_url":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026","og_site_name":"bwin news","article_published_time":"2026-07-13T18:57:52+00:00","article_modified_time":"2026-07-13T18:57:53+00:00","og_image":[{"width":1874,"height":1249,"url":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/og-image\/immagine-scommesse-francia-spagna-bwin-news-watermarked-b22c3735f1ea642385f343e5cf117991.jpg","type":"image\/jpeg"}],"author":"Emanuele Celeste","twitter_misc":{"Scritto da":"Emanuele Celeste","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#article","isPartOf":{"@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026"},"author":{"name":"Emanuele Celeste","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/fe0357b991a70902eeb82d9f3973e452"},"headline":"Francia-Spagna: semifinale tra le grandi favorite del Mondiale","datePublished":"2026-07-13T18:57:52+00:00","dateModified":"2026-07-13T18:57:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026"},"wordCount":485,"publisher":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#organization"},"articleSection":["Infografiche sullo Sport e Approfondimenti","Mondiali 2026"],"inLanguage":"it-IT","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.bwin.it\/it\/news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026","url":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026","name":"quote Francia Spagna: il pronostico sui Bleus","isPartOf":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#website"},"datePublished":"2026-07-13T18:57:52+00:00","dateModified":"2026-07-13T18:57:53+00:00","description":"Le quote Francia Spagna: il pronostico sull'atteso incontro valido per la prima semifinale dei Mondiali 2026.","breadcrumb":{"@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026\/quote-francia-spagna-scommesse-pronostico-14-7-2026#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sports.bwin.it\/it\/news\/"},{"@type":"ListItem","position":2,"name":"Mondiali 2026","item":"https:\/\/www.bwin.it\/it\/news\/mondiali-2026"},{"@type":"ListItem","position":3,"name":"Francia-Spagna: semifinale tra le grandi favorite del Mondiale"}]},{"@type":"WebSite","@id":"https:\/\/sports.bwin.it\/it\/news\/#website","url":"https:\/\/sports.bwin.it\/it\/news\/","name":"bwin news","description":"","publisher":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sports.bwin.it\/it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sports.bwin.it\/it\/news\/#organization","name":"bwin news","url":"https:\/\/sports.bwin.it\/it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png","contentUrl":"https:\/\/www.bwin.it\/it\/news\/wp-content\/uploads\/2023\/04\/cropped-1060x400-bwin.news_.png","width":1060,"height":400,"caption":"bwin news"},"image":{"@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/fe0357b991a70902eeb82d9f3973e452","name":"Emanuele Celeste","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sports.bwin.it\/it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f38a8b15ffff50d003d266ca22a08912?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f38a8b15ffff50d003d266ca22a08912?s=96&d=mm&r=g","caption":"Emanuele Celeste"},"description":"Attivo nel campo della comunicazione e dell'informazione dal 2007. Grazie alla lunga esperienza presso eventi e conferenze pu\u00f2 vantare in bacheca centinaia di interventi radiotelevisivi anche con personaggi del mondo dello spettacolo e dello sport, mentre gli incarichi da social media manager lo hanno portato a scoprire anche gli angoli pi\u00f9 remoti della rete. Non perde mai di vista tutto ci\u00f2 che \u00e8 di attualit\u00e0.","url":"https:\/\/www.bwin.it\/it\/news\/author\/e-celeste"}]}},"_links":{"self":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/585761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/comments?post=585761"}],"version-history":[{"count":1,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/585761\/revisions"}],"predecessor-version":[{"id":585766,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/posts\/585761\/revisions\/585766"}],"wp:attachment":[{"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/media?parent=585761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/categories?post=585761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bwin.it\/it\/news\/wp-json\/wp\/v2\/tags?post=585761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}